{"id":399,"date":"2022-07-14T18:45:42","date_gmt":"2022-07-14T22:45:42","guid":{"rendered":"https:\/\/middlesexcollege.edu\/event-services\/?page_id=399"},"modified":"2026-05-04T13:29:02","modified_gmt":"2026-05-04T17:29:02","slug":"middlesex-college-facility-rentals","status":"publish","type":"page","link":"https:\/\/middlesexcollege.edu\/event-services\/","title":{"rendered":"Facility Rentals"},"content":{"rendered":"\n<h2 class=\"bb-primary-1 wp-block-heading\">Our spacious rooms include:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conference rooms<\/li>\n\n\n\n<li>Classrooms<\/li>\n\n\n\n<li>Computer labs<\/li>\n\n\n\n<li>Multipurpose rooms<\/li>\n\n\n\n<li>Theaters<\/li>\n\n\n\n<li>Recreational facilities<\/li>\n<\/ul>\n\n\n\n<h2 class=\"bb-primary-1 wp-block-heading\"><em>Plus!<\/em>&nbsp;All our facilities provide:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Free parking<\/li>\n\n\n\n<li>Free Wi-Fi<\/li>\n\n\n\n<li>Wheelchair accessibility<\/li>\n\n\n\n<li>Audio-visual equipment<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Hold your next event at Middlesex\u00a0College<\/p>\n","protected":false},"author":1,"featured_media":406,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-399","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Facility Rentals | Middlesex College<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/middlesexcollege.edu\/event-services\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Facility Rentals | Middlesex College\" \/>\n<meta property=\"og:description\" content=\"Hold your next event at Middlesex\u00a0College\" \/>\n<meta property=\"og:url\" content=\"https:\/\/middlesexcollege.edu\/event-services\/\" \/>\n<meta property=\"og:site_name\" content=\"Facility Rentals\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T17:29:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/middlesexcollege.edu\/event-services\/wp-content\/uploads\/sites\/18\/2022\/07\/event-services.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"615\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/\",\"url\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/\",\"name\":\"Facility Rentals | Middlesex College\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2022\\\/07\\\/event-services.jpg\",\"datePublished\":\"2022-07-14T22:45:42+00:00\",\"dateModified\":\"2026-05-04T17:29:02+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/#primaryimage\",\"url\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2022\\\/07\\\/event-services.jpg\",\"contentUrl\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2022\\\/07\\\/event-services.jpg\",\"width\":1920,\"height\":615},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/#website\",\"url\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/\",\"name\":\"Facility Rentals\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/#organization\",\"name\":\"Facility Rentals\",\"url\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test-www.middlesexcc.edu\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2022\\\/05\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/test-www.middlesexcc.edu\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2022\\\/05\\\/logo.png\",\"width\":233,\"height\":67,\"caption\":\"Facility Rentals\"},\"image\":{\"@id\":\"https:\\\/\\\/middlesexcollege.edu\\\/event-services\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Facility Rentals | Middlesex College","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/middlesexcollege.edu\/event-services\/","og_locale":"en_US","og_type":"article","og_title":"Facility Rentals | Middlesex College","og_description":"Hold your next event at Middlesex\u00a0College","og_url":"https:\/\/middlesexcollege.edu\/event-services\/","og_site_name":"Facility Rentals","article_modified_time":"2026-05-04T17:29:02+00:00","og_image":[{"width":1920,"height":615,"url":"https:\/\/middlesexcollege.edu\/event-services\/wp-content\/uploads\/sites\/18\/2022\/07\/event-services.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/middlesexcollege.edu\/event-services\/","url":"https:\/\/middlesexcollege.edu\/event-services\/","name":"Facility Rentals | Middlesex College","isPartOf":{"@id":"https:\/\/middlesexcollege.edu\/event-services\/#website"},"primaryImageOfPage":{"@id":"https:\/\/middlesexcollege.edu\/event-services\/#primaryimage"},"image":{"@id":"https:\/\/middlesexcollege.edu\/event-services\/#primaryimage"},"thumbnailUrl":"https:\/\/middlesexcollege.edu\/event-services\/wp-content\/uploads\/sites\/18\/2022\/07\/event-services.jpg","datePublished":"2022-07-14T22:45:42+00:00","dateModified":"2026-05-04T17:29:02+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/middlesexcollege.edu\/event-services\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/middlesexcollege.edu\/event-services\/#primaryimage","url":"https:\/\/middlesexcollege.edu\/event-services\/wp-content\/uploads\/sites\/18\/2022\/07\/event-services.jpg","contentUrl":"https:\/\/middlesexcollege.edu\/event-services\/wp-content\/uploads\/sites\/18\/2022\/07\/event-services.jpg","width":1920,"height":615},{"@type":"WebSite","@id":"https:\/\/middlesexcollege.edu\/event-services\/#website","url":"https:\/\/middlesexcollege.edu\/event-services\/","name":"Facility Rentals","description":"","publisher":{"@id":"https:\/\/middlesexcollege.edu\/event-services\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/middlesexcollege.edu\/event-services\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/middlesexcollege.edu\/event-services\/#organization","name":"Facility Rentals","url":"https:\/\/middlesexcollege.edu\/event-services\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/middlesexcollege.edu\/event-services\/#\/schema\/logo\/image\/","url":"https:\/\/test-www.middlesexcc.edu\/wp-content\/uploads\/sites\/18\/2022\/05\/logo.png","contentUrl":"https:\/\/test-www.middlesexcc.edu\/wp-content\/uploads\/sites\/18\/2022\/05\/logo.png","width":233,"height":67,"caption":"Facility Rentals"},"image":{"@id":"https:\/\/middlesexcollege.edu\/event-services\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/middlesexcollege.edu\/event-services\/wp-json\/wp\/v2\/pages\/399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/middlesexcollege.edu\/event-services\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/middlesexcollege.edu\/event-services\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/middlesexcollege.edu\/event-services\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/middlesexcollege.edu\/event-services\/wp-json\/wp\/v2\/comments?post=399"}],"version-history":[{"count":10,"href":"https:\/\/middlesexcollege.edu\/event-services\/wp-json\/wp\/v2\/pages\/399\/revisions"}],"predecessor-version":[{"id":515,"href":"https:\/\/middlesexcollege.edu\/event-services\/wp-json\/wp\/v2\/pages\/399\/revisions\/515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/middlesexcollege.edu\/event-services\/wp-json\/wp\/v2\/media\/406"}],"wp:attachment":[{"href":"https:\/\/middlesexcollege.edu\/event-services\/wp-json\/wp\/v2\/media?parent=399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}